
{"id":9297,"date":"2022-09-23T19:40:11","date_gmt":"2022-09-23T17:40:11","guid":{"rendered":"https:\/\/www.cosmapack.it\/new\/?page_id=9297"},"modified":"2026-02-18T13:09:36","modified_gmt":"2026-02-18T12:09:36","slug":"lavaggio-cassette-lavatrice-cassette","status":"publish","type":"page","link":"https:\/\/www.cosmapack.it\/new\/lavaggio-cassette-lavatrice-cassette\/","title":{"rendered":"Lavaggio Cassette &#8211; lavatrice cassette"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space height=&#8221;55px&#8221;][\/vc_column][\/vc_row][vc_row el_class=&#8221;gino&#8221;][vc_column width=&#8221;1\/6&#8243;][vc_icon icon_fontawesome=&#8221;far fa-caret-square-left&#8221; color=&#8221;custom&#8221; size=&#8221;lg&#8221; custom_color=&#8221;#afafaf&#8221; link=&#8221;url:%2Fnew%2Flavaggio-cassette%2F&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #525252; font-family: opensans;\"><span style=\"color: #525252; font-size: 24pt;\">LAVATRICE CASSETTE<br \/><\/span><\/span><\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;gino&#8221; css=&#8221;.vc_custom_1631123609879{margin-bottom: -30px !important;border-radius: 2px !important;}&#8221;][vc_column][vc_row_inner css=&#8221;.vc_custom_1631017979314{margin-top: -20px !important;}&#8221;][vc_column_inner][vc_column_text]<\/p>\n    <div id=\"6a57808c97150\" rel=\"9301\" data-gg-autoplay=\"auto\" class=\"gg_galleria_slider_wrap gg_galleria_slider_light gg_galleria_slider_show_thumbs gg_slider_no_borders gg_galleria_responsive ggs_9301\" style=\"width: 100%; \" data-asp-ratio=\"0.45\"><a href=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice-cassette.jpg\"><img src=\"\/\/www.cosmapack.it\/new\/wp-content\/uploads\/ewpt_cache\/100x60_90_1_c_FFFFFF_d8c4ff36398f7481ace425220d358dee.jpg\" data-big=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice-cassette.jpg\" data-description=\"\" alt=\"lavatrice cassette\" \/><\/a><a href=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/schermata-2020-09-30-alle-16.20.13-736x512-1.png\"><img src=\"\/\/www.cosmapack.it\/new\/wp-content\/uploads\/ewpt_cache\/100x60_90_1_c_FFFFFF_6dcf92c0d82bca3f2eee72b8a02986a0.png\" data-big=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/schermata-2020-09-30-alle-16.20.13-736x512-1.png\" data-description=\"\" alt=\"schermata-2020-09-30-alle-16.20.13-736x512\" \/><\/a><a href=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice3.jpg\"><img src=\"\/\/www.cosmapack.it\/new\/wp-content\/uploads\/ewpt_cache\/100x60_90_1_c_FFFFFF_919acd1cbe47763e6533703ccd6322cf.jpg\" data-big=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice3.jpg\" data-description=\"\" alt=\"lavatrice3\" \/><\/a><a href=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice2.jpg\"><img src=\"\/\/www.cosmapack.it\/new\/wp-content\/uploads\/ewpt_cache\/100x60_90_1_c_FFFFFF_ae145080e03f1b5596d2afdae220f5e6.jpg\" data-big=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice2.jpg\" data-description=\"\" alt=\"lavatrice2\" \/><\/a><a href=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice1.jpg\"><img src=\"\/\/www.cosmapack.it\/new\/wp-content\/uploads\/ewpt_cache\/100x60_90_1_c_FFFFFF_4b20629c0fe3a2bd90369fbd87448298.jpg\" data-big=\"https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2021\/06\/lavatrice1.jpg\" data-description=\"\" alt=\"lavatrice1\" \/><\/a>        <div style=\"clear: both;\"><\/div><\/div>    <script type=\"text\/javascript\"> (function($) {         \"use strict\";                 $(document).ready(function($) {             if(typeof(gg_galleria_init) == \"function\") {                 gg_galleria_show(\"#6a57808c97150\");                gg_galleria_init(\"#6a57808c97150\");            }        });    })(jQuery);   <\/script>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; color: #525252;\"><strong><span style=\"font-family: opensans;\">Forniamo lavatrici di cassette in collaborazione cn il nostro partner Velox Barchitta, Le lavatrici sono dei sistemi di lavaggio a tunnel. Possono essere fornite con tetto apribile e possono ricevere le cassette su una o due linee. Abbiamo installato con successo lavatrici da 5000 cassette\/ora.<\/span><\/strong><\/span><\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1648900374250{margin-top: -13px !important;}&#8221;]<\/p>\n<p style=\"text-align: right;\"><a href='\/new\/dove-siamo\/' onclick='' class='wpi_designer_button   wpi_shadow wpi_shadow_no wpi_text_shadow_no wpi_texture_no wpi_border_all wpi_padding_7px wpi_10px wpi_designer_button_4221 wpi_icon wpi_icon_no wpi_icon_left  ' target='' rel=''><i class=''><\/i><span class='wpi_text'>Ottieni un preventivo<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_raw_html]JTNDYSUyMG5hbWUlM0QlMjJ2aWRlbyUyMiUzRQ==[\/vc_raw_html][vc_column_text]<\/p>\n<hr class=\"new1\" \/>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;gino&#8221;][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;gino&#8221;][vc_column][vc_raw_html css=&#8221;.vc_custom_1663955015690{background-color: #ffffff !important;}&#8221;]JTNDdmlkZW8lMjBwbGF5c2lubGluZSUyMGNvbnRyb2xzJTIwbm9mdWxsc2NyZWVuJTIwY29udHJvbHNMaXN0JTNEJTIybm9kb3dubG9hZCUyMG5vZnVsbHNjcmVlbiUyMG5vcGxheWJhY2tyYXRlJTIyJTIwd2lkdGglM0QlMjIxMDAlMjUlMjIlMjBoZWlnaHQlM0QlMjIxMDAlMjUlMjIlMjBwb3N0ZXIlM0QlMjJodHRwcyUzQSUyRiUyRnd3dy5jb3NtYXBhY2suaXQlMkZuZXclMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjElMkYwNiUyRjA4LWZyYW1lLWxhdmF0cmljZS1jYXNzZXR0ZS5qcGclMjIlM0UlMEElM0Nzb3VyY2UlMjBzcmMlM0QlMjJodHRwcyUzQSUyRiUyRnd3dy5jb3NtYXBhY2suaXQlMkZuZXclMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjElMkYwNiUyRjA4LUxhdmFnZ2lvQ2Fzc2V0dGVfNzIwX2l0Lm1wNCUyMiUyMCUyRiUzRSUwQSUzQyUyRnZpZGVvJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1648909655613{margin-top: 100px !important;background-color: #f4f4f4 !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<div id=\"examples\">\n<div class=\"example\">\n<p style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span class=\"hover hover-1\" style=\"color: #000000;\">SEI INTERES<\/span><span style=\"font-size: 30px;\"><span style=\"color: #000000;\">SATO<\/span><span style=\"color: #ed0000;\"> AI NOSTRI PRODOTTI?<\/span><\/span><\/span><\/p>\n<\/div>\n<\/div>\n<p>[vc_empty_space height=&#8221;10px&#8221;]<\/p>\n<div align=\"center\">\n<ul>\n<li class=\"fas fa-phone-alt colors30\" style=\"text-align: center;\"><span style=\"color: #333333; font-size: 30px; font-family: Arial;\"> +39 080 4968989<\/span><\/li>\n<\/ul>\n<\/div>\n<p>[vc_empty_space height=&#8221;10px&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18px; font-family: Arial, Helvetica, sans-serif; line-height: 12px; color: #000000;\">Mettiamo a vostra disposizione un consulente che vi ascolter\u00e0 e<br \/>vi indirizzer\u00e0 verso la soluzione ideale al vostro caso. Il nostro successo \u00e8 in ogni<br \/>cliente pienamente soddisfatto.<\/span><\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;gino&#8221; css=&#8221;.vc_custom_1647862614827{margin-top: -40px !important;}&#8221;]<\/p>\n<div align=\"center\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-5861\"><form id=\"wpforms-form-5861\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"5861\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/new\/wp-json\/wp\/v2\/pages\/9297\" data-token=\"7758fe713264ceb310aee0c541e23c11\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-5861-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-5861-field_0\">Nome <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-5861-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-5861-field_3-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-5861-field_3\">Cognome <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-5861-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-5861-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-5861-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-5861-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-5861-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-5861-field_2\">Messaggio <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-5861-field_2\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"5861\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"3\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5861\" class=\"wpforms-submit\" data-alt-text=\"Invio in corso...\" data-submit-text=\"RICHIEDI INFORMAZIONI &gt;&gt;\" aria-live=\"assertive\" value=\"wpforms-submit\">RICHIEDI INFORMAZIONI &gt;&gt;<\/button><img src=\"https:\/\/www.cosmapack.it\/new\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; columns_placement=&#8221;top&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; el_class=&#8221;ginofoot&#8221; css=&#8221;.vc_custom_1646673260486{background: #818181 url(https:\/\/www.cosmapack.it\/new\/wp-content\/uploads\/2022\/03\/footer1_def1.png?id=6749) !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<div class=\"coloresocial\" align=\"center\">\n<p><a class=\"fab fa-youtube colors1\" href=\"https:\/\/www.youtube.com\/user\/cosmapack\"><\/a>\u00a0\u00a0\u00a0\u00a0<a class=\"fab fa-facebook-square colors1\" href=\"https:\/\/it-it.facebook.com\/cosmapack\/\"><\/a>\u00a0\u00a0\u00a0\u00a0<a class=\"fab fa-linkedin colors1\" href=\"https:\/\/it.linkedin.com\/company\/cosmapack-international-s.r.l.\"><\/a><\/p>\n<hr class=\"new4\" \/>\n<p style=\"line-height: 20px; margin: 15px;\"><span style=\"font-family: Arial; font-size: 14px; color: #ffffff;\">Tieniti sempre informato,<\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 14px; color: #ffffff;\">visita i nostri canali social<\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 14px; color: #ffffff;\">e scoprirai tante novit\u00e0.<\/span><\/p>\n<\/div>\n<p>[\/vc_column_text][vc_single_image image=&#8221;6693&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<div class=\"coloresocial\" align=\"center\">\n<ul>\n<li class=\"fas fa-home colors\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 17px; color: #ffffff; font-weight: 400;\">\u00a0C.da Montaltino n.c.<br \/>70044, Polignano a Mare (BA)<br \/>Italy<\/span><\/li>\n<\/ul>\n<ul>\n<li class=\"fas fa-phone colors\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 17px; color: #ffffff; font-weight: 400;\"> +39 080 4968989<\/span><\/li>\n<\/ul>\n<ul>\n<li class=\"fas fa-envelope colors\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 17px; color: #ffffff; font-weight: 400;\"> info@cosmapack.it<\/span><\/li>\n<\/ul>\n<ul>\n<li class=\"fas fa-copy colors\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 17px; color: #ffffff; font-weight: 400;\"> VAT: IT05375680724<\/span><\/li>\n<\/ul>\n<ul>\n<li class=\"fas fa-link colors\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 17px; color: #ffffff; font-weight: 400;\"> SDI: cosmapack.fe@pec.it<\/span><\/li>\n<\/ul>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;6712&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;6746&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1648908576891{margin-top: -35px !important;background-color: #818181 !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10px;\"><span style=\"font-family: opensans;\"><span style=\"font-size: 14px; color: #ffffff;\">Realized by: <a href=\"https:\/\/www.vgtechnology.it\/\" style=\"color: #ffffff!important;\">V&amp;G Technology<\/a> &#8211; Concept: Cisternino Francesco<\/span><\/span><br \/><\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;55px&#8221;][\/vc_column][\/vc_row][vc_row el_class=&#8221;gino&#8221;][vc_column width=&#8221;1\/6&#8243;][vc_icon icon_fontawesome=&#8221;far fa-caret-square-left&#8221; color=&#8221;custom&#8221; size=&#8221;lg&#8221; custom_color=&#8221;#afafaf&#8221; link=&#8221;url:%2Fnew%2Flavaggio-cassette%2F&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text] LAVATRICE CASSETTE [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;gino&#8221; css=&#8221;.vc_custom_1631123609879{margin-bottom: -30px !important;border-radius: 2px !important;}&#8221;][vc_column][vc_row_inner css=&#8221;.vc_custom_1631017979314{margin-top: -20px !important;}&#8221;][vc_column_inner][vc_column_text] [\/vc_column_text][vc_column_text] Forniamo lavatrici di cassette in collaborazione cn il nostro partner Velox Barchitta, Le lavatrici sono dei sistemi di lavaggio a tunnel. Possono essere fornite con tetto apribile e possono ricevere [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"lang":"it","translations":{"en":9700,"it":9297},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/pages\/9297"}],"collection":[{"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/comments?post=9297"}],"version-history":[{"count":3,"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/pages\/9297\/revisions"}],"predecessor-version":[{"id":9308,"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/pages\/9297\/revisions\/9308"}],"wp:attachment":[{"href":"https:\/\/www.cosmapack.it\/new\/wp-json\/wp\/v2\/media?parent=9297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}